{"id":70,"date":"2023-07-06T13:01:42","date_gmt":"2023-07-06T13:01:42","guid":{"rendered":"https:\/\/www.clinica-sante.com\/ro\/?page_id=70"},"modified":"2026-03-20T09:36:06","modified_gmt":"2026-03-20T07:36:06","slug":"contact","status":"publish","type":"page","link":"https:\/\/www.clinica-sante.com\/ro\/contact\/","title":{"rendered":"Contact"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/Contact.php","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-70","page","type-page","status-publish","hentry"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.clinica-sante.com\/ro\/contact\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"ro_RO\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Clinica Sante - Laborator de Analize Medicale - Clinica Sante - Laborator de Analize Medicale\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Contact - Clinica Sante - Laborator de Analize Medicale\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.clinica-sante.com\/ro\/contact\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-07-06T13:01:42+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-03-20T07:36:06+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Contact - Clinica Sante - Laborator de Analize Medicale\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.clinica-sante.com\\\/ro\\\/contact\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.clinica-sante.com\\\/ro#listItem\",\"position\":1,\"name\":\"Prima pagin\\u0103\",\"item\":\"https:\\\/\\\/www.clinica-sante.com\\\/ro\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.clinica-sante.com\\\/ro\\\/contact\\\/#listItem\",\"name\":\"Contact\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.clinica-sante.com\\\/ro\\\/contact\\\/#listItem\",\"position\":2,\"name\":\"Contact\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.clinica-sante.com\\\/ro#listItem\",\"name\":\"Prima pagin\\u0103\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.clinica-sante.com\\\/ro\\\/#organization\",\"name\":\"Clinica Sante - Laborator de Analize Medicale\",\"description\":\"Clinica Sante - Laborator de Analize Medicale Clinica Sante - Laborator de Analize Medicale - Clinica Sante - Laborator de Analize Medicale\",\"url\":\"https:\\\/\\\/www.clinica-sante.com\\\/ro\\\/\",\"telephone\":\"+40376448099\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.clinica-sante.com\\\/ro\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Necesar-website-nou-CS-Romania_Logo-1024x1024-1.png\",\"@id\":\"https:\\\/\\\/www.clinica-sante.com\\\/ro\\\/contact\\\/#organizationLogo\",\"width\":1024,\"height\":1024},\"image\":{\"@id\":\"https:\\\/\\\/www.clinica-sante.com\\\/ro\\\/contact\\\/#organizationLogo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.clinica-sante.com\\\/ro\\\/contact\\\/#webpage\",\"url\":\"https:\\\/\\\/www.clinica-sante.com\\\/ro\\\/contact\\\/\",\"name\":\"Contact - Clinica Sante - Laborator de Analize Medicale\",\"inLanguage\":\"ro-RO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.clinica-sante.com\\\/ro\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.clinica-sante.com\\\/ro\\\/contact\\\/#breadcrumblist\"},\"datePublished\":\"2023-07-06T13:01:42+03:00\",\"dateModified\":\"2026-03-20T09:36:06+03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.clinica-sante.com\\\/ro\\\/#website\",\"url\":\"https:\\\/\\\/www.clinica-sante.com\\\/ro\\\/\",\"name\":\"Clinica Sante - Laborator de Analize Medicale\",\"alternateName\":\"CLINICA SANTE ROMANIA\",\"description\":\"Clinica Sante - Laborator de Analize Medicale\",\"inLanguage\":\"ro-RO\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.clinica-sante.com\\\/ro\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Contact - Clinica Sante - Laborator de Analize Medicale<\/title>\n\n","aioseo_head_json":{"title":"Contact - Clinica Sante - Laborator de Analize Medicale","description":"","canonical_url":"https:\/\/www.clinica-sante.com\/ro\/contact\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.clinica-sante.com\/ro\/contact\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.clinica-sante.com\/ro#listItem","position":1,"name":"Prima pagin\u0103","item":"https:\/\/www.clinica-sante.com\/ro","nextItem":{"@type":"ListItem","@id":"https:\/\/www.clinica-sante.com\/ro\/contact\/#listItem","name":"Contact"}},{"@type":"ListItem","@id":"https:\/\/www.clinica-sante.com\/ro\/contact\/#listItem","position":2,"name":"Contact","previousItem":{"@type":"ListItem","@id":"https:\/\/www.clinica-sante.com\/ro#listItem","name":"Prima pagin\u0103"}}]},{"@type":"Organization","@id":"https:\/\/www.clinica-sante.com\/ro\/#organization","name":"Clinica Sante - Laborator de Analize Medicale","description":"Clinica Sante - Laborator de Analize Medicale Clinica Sante - Laborator de Analize Medicale - Clinica Sante - Laborator de Analize Medicale","url":"https:\/\/www.clinica-sante.com\/ro\/","telephone":"+40376448099","logo":{"@type":"ImageObject","url":"https:\/\/www.clinica-sante.com\/ro\/wp-content\/uploads\/2024\/04\/Necesar-website-nou-CS-Romania_Logo-1024x1024-1.png","@id":"https:\/\/www.clinica-sante.com\/ro\/contact\/#organizationLogo","width":1024,"height":1024},"image":{"@id":"https:\/\/www.clinica-sante.com\/ro\/contact\/#organizationLogo"}},{"@type":"WebPage","@id":"https:\/\/www.clinica-sante.com\/ro\/contact\/#webpage","url":"https:\/\/www.clinica-sante.com\/ro\/contact\/","name":"Contact - Clinica Sante - Laborator de Analize Medicale","inLanguage":"ro-RO","isPartOf":{"@id":"https:\/\/www.clinica-sante.com\/ro\/#website"},"breadcrumb":{"@id":"https:\/\/www.clinica-sante.com\/ro\/contact\/#breadcrumblist"},"datePublished":"2023-07-06T13:01:42+03:00","dateModified":"2026-03-20T09:36:06+03:00"},{"@type":"WebSite","@id":"https:\/\/www.clinica-sante.com\/ro\/#website","url":"https:\/\/www.clinica-sante.com\/ro\/","name":"Clinica Sante - Laborator de Analize Medicale","alternateName":"CLINICA SANTE ROMANIA","description":"Clinica Sante - Laborator de Analize Medicale","inLanguage":"ro-RO","publisher":{"@id":"https:\/\/www.clinica-sante.com\/ro\/#organization"}}]},"og:locale":"ro_RO","og:site_name":"Clinica Sante - Laborator de Analize Medicale - Clinica Sante - Laborator de Analize Medicale","og:type":"article","og:title":"Contact - Clinica Sante - Laborator de Analize Medicale","og:url":"https:\/\/www.clinica-sante.com\/ro\/contact\/","article:published_time":"2023-07-06T13:01:42+00:00","article:modified_time":"2026-03-20T07:36:06+00:00","twitter:card":"summary_large_image","twitter:title":"Contact - Clinica Sante - Laborator de Analize Medicale"},"aioseo_meta_data":{"post_id":"70","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"contact","score":100,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":[],"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":1},"keyphraseInURL":{"score":5,"maxScore":5,"error":0}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2026-03-20 07:49:55","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2023-07-21 09:31:20","updated":"2026-03-20 08:34:21"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.clinica-sante.com\/ro\" title=\"Prima pagin\u0103\">Prima pagin\u0103<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tContact\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Prima pagin\u0103","link":"https:\/\/www.clinica-sante.com\/ro"},{"label":"Contact","link":"https:\/\/www.clinica-sante.com\/ro\/contact\/"}],"_links":{"self":[{"href":"https:\/\/www.clinica-sante.com\/ro\/wp-json\/wp\/v2\/pages\/70","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.clinica-sante.com\/ro\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.clinica-sante.com\/ro\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.clinica-sante.com\/ro\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.clinica-sante.com\/ro\/wp-json\/wp\/v2\/comments?post=70"}],"version-history":[{"count":24,"href":"https:\/\/www.clinica-sante.com\/ro\/wp-json\/wp\/v2\/pages\/70\/revisions"}],"predecessor-version":[{"id":30123,"href":"https:\/\/www.clinica-sante.com\/ro\/wp-json\/wp\/v2\/pages\/70\/revisions\/30123"}],"wp:attachment":[{"href":"https:\/\/www.clinica-sante.com\/ro\/wp-json\/wp\/v2\/media?parent=70"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}