{"id":434,"count":10,"description":"","link":"https:\/\/www.clinica-sante.com\/ro\/judete\/suceava\/","name":"Suceava","slug":"suceava","taxonomy":"judete","parent":0,"meta":[],"acf":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.clinica-sante.com\/ro\/judete\/suceava\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"ro_RO\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Clinica Sante - Laborator de Analize Medicale - Clinica Sante - Laborator de Analize Medicale\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Suceava - Clinica Sante - Laborator de Analize Medicale\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.clinica-sante.com\/ro\/judete\/suceava\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Suceava - Clinica Sante - Laborator de Analize Medicale\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.clinica-sante.com\\\/ro\\\/wp-json\\\/wp\\\/v2\\\/judete\\\/434\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.clinica-sante.com\\\/ro#listItem\",\"position\":1,\"name\":\"Prima pagin\\u0103\",\"item\":\"https:\\\/\\\/www.clinica-sante.com\\\/ro\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.clinica-sante.com\\\/ro\\\/judete\\\/suceava\\\/#listItem\",\"name\":\"Suceava\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.clinica-sante.com\\\/ro\\\/judete\\\/suceava\\\/#listItem\",\"position\":2,\"name\":\"Suceava\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.clinica-sante.com\\\/ro#listItem\",\"name\":\"Prima pagin\\u0103\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.clinica-sante.com\\\/ro\\\/wp-json\\\/wp\\\/v2\\\/judete\\\/434\\\/#collectionpage\",\"url\":\"https:\\\/\\\/www.clinica-sante.com\\\/ro\\\/wp-json\\\/wp\\\/v2\\\/judete\\\/434\\\/\",\"name\":\"Suceava - Clinica Sante - Laborator de Analize Medicale\",\"inLanguage\":\"ro-RO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.clinica-sante.com\\\/ro\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.clinica-sante.com\\\/ro\\\/wp-json\\\/wp\\\/v2\\\/judete\\\/434\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.clinica-sante.com\\\/ro\\\/#organization\",\"name\":\"Clinica Sante - Laborator de Analize Medicale\",\"description\":\"Clinica Sante - Laborator de Analize Medicale Clinica Sante - Laborator de Analize Medicale - Clinica Sante - Laborator de Analize Medicale\",\"url\":\"https:\\\/\\\/www.clinica-sante.com\\\/ro\\\/\",\"telephone\":\"+40376448099\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.clinica-sante.com\\\/ro\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Necesar-website-nou-CS-Romania_Logo-1024x1024-1.png\",\"@id\":\"https:\\\/\\\/www.clinica-sante.com\\\/ro\\\/wp-json\\\/wp\\\/v2\\\/judete\\\/434\\\/#organizationLogo\",\"width\":1024,\"height\":1024},\"image\":{\"@id\":\"https:\\\/\\\/www.clinica-sante.com\\\/ro\\\/wp-json\\\/wp\\\/v2\\\/judete\\\/434\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.clinica-sante.com\\\/ro\\\/#website\",\"url\":\"https:\\\/\\\/www.clinica-sante.com\\\/ro\\\/\",\"name\":\"Clinica Sante - Laborator de Analize Medicale\",\"alternateName\":\"CLINICA SANTE ROMANIA\",\"description\":\"Clinica Sante - Laborator de Analize Medicale\",\"inLanguage\":\"ro-RO\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.clinica-sante.com\\\/ro\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Suceava - Clinica Sante - Laborator de Analize Medicale<\/title>\n\n","aioseo_head_json":{"title":"Suceava - Clinica Sante - Laborator de Analize Medicale","description":"","canonical_url":"https:\/\/www.clinica-sante.com\/ro\/judete\/suceava\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.clinica-sante.com\/ro\/wp-json\/wp\/v2\/judete\/434\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.clinica-sante.com\/ro#listItem","position":1,"name":"Prima pagin\u0103","item":"https:\/\/www.clinica-sante.com\/ro","nextItem":{"@type":"ListItem","@id":"https:\/\/www.clinica-sante.com\/ro\/judete\/suceava\/#listItem","name":"Suceava"}},{"@type":"ListItem","@id":"https:\/\/www.clinica-sante.com\/ro\/judete\/suceava\/#listItem","position":2,"name":"Suceava","previousItem":{"@type":"ListItem","@id":"https:\/\/www.clinica-sante.com\/ro#listItem","name":"Prima pagin\u0103"}}]},{"@type":"CollectionPage","@id":"https:\/\/www.clinica-sante.com\/ro\/wp-json\/wp\/v2\/judete\/434\/#collectionpage","url":"https:\/\/www.clinica-sante.com\/ro\/wp-json\/wp\/v2\/judete\/434\/","name":"Suceava - Clinica Sante - Laborator de Analize Medicale","inLanguage":"ro-RO","isPartOf":{"@id":"https:\/\/www.clinica-sante.com\/ro\/#website"},"breadcrumb":{"@id":"https:\/\/www.clinica-sante.com\/ro\/wp-json\/wp\/v2\/judete\/434\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/www.clinica-sante.com\/ro\/#organization","name":"Clinica Sante - Laborator de Analize Medicale","description":"Clinica Sante - Laborator de Analize Medicale Clinica Sante - Laborator de Analize Medicale - Clinica Sante - Laborator de Analize Medicale","url":"https:\/\/www.clinica-sante.com\/ro\/","telephone":"+40376448099","logo":{"@type":"ImageObject","url":"https:\/\/www.clinica-sante.com\/ro\/wp-content\/uploads\/2024\/04\/Necesar-website-nou-CS-Romania_Logo-1024x1024-1.png","@id":"https:\/\/www.clinica-sante.com\/ro\/wp-json\/wp\/v2\/judete\/434\/#organizationLogo","width":1024,"height":1024},"image":{"@id":"https:\/\/www.clinica-sante.com\/ro\/wp-json\/wp\/v2\/judete\/434\/#organizationLogo"}},{"@type":"WebSite","@id":"https:\/\/www.clinica-sante.com\/ro\/#website","url":"https:\/\/www.clinica-sante.com\/ro\/","name":"Clinica Sante - Laborator de Analize Medicale","alternateName":"CLINICA SANTE ROMANIA","description":"Clinica Sante - Laborator de Analize Medicale","inLanguage":"ro-RO","publisher":{"@id":"https:\/\/www.clinica-sante.com\/ro\/#organization"}}]},"og:locale":"ro_RO","og:site_name":"Clinica Sante - Laborator de Analize Medicale - Clinica Sante - Laborator de Analize Medicale","og:type":"article","og:title":"Suceava - Clinica Sante - Laborator de Analize Medicale","og:url":"https:\/\/www.clinica-sante.com\/ro\/judete\/suceava\/","twitter:card":"summary_large_image","twitter:title":"Suceava - Clinica Sante - Laborator de Analize Medicale"},"aioseo_meta_data":{"term_id":"434","title":null,"description":null,"keywords":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_custom_url":null,"og_image_custom_fields":null,"og_custom_image_width":null,"og_custom_image_height":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","tabs":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-14 09:25:03","focus_keyword":null,"additional_keywords":null,"truseo_locale":null,"breadcrumb_settings":null,"created":"2023-07-25 16:23:16","updated":"2026-05-14 09:25:03","og_image_url":null,"og_image_width":null,"og_image_height":null,"twitter_image_url":null,"pillar_content":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.clinica-sante.com\/ro\" title=\"Prima pagin\u0103\">Prima pagin\u0103<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tSuceava\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Prima pagin\u0103","link":"https:\/\/www.clinica-sante.com\/ro"},{"label":"Suceava","link":"https:\/\/www.clinica-sante.com\/ro\/judete\/suceava\/"}],"_links":{"self":[{"href":"https:\/\/www.clinica-sante.com\/ro\/wp-json\/wp\/v2\/judete\/434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.clinica-sante.com\/ro\/wp-json\/wp\/v2\/judete"}],"about":[{"href":"https:\/\/www.clinica-sante.com\/ro\/wp-json\/wp\/v2\/taxonomies\/judete"}],"wp:post_type":[{"href":"https:\/\/www.clinica-sante.com\/ro\/wp-json\/wp\/v2\/locatii?judete=434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}